{"id":727,"count":1,"description":"","link":"https:\/\/www.enginecompare.co.uk\/blog\/tag\/citroen-relay-best-engines\/","name":"Citroen Relay Best Engines","slug":"citroen-relay-best-engines","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/tags\/727"}],"collection":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/posts?tags=727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}