{"id":724,"count":3,"description":"","link":"https:\/\/www.enginecompare.co.uk\/blog\/tag\/citroen-relay-engines\/","name":"Citroen Relay Engines","slug":"citroen-relay-engines","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/tags\/724"}],"collection":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.enginecompare.co.uk\/blog\/wp-json\/wp\/v2\/posts?tags=724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}